{"id":10995,"date":"2022-05-27T11:46:57","date_gmt":"2022-05-27T10:46:57","guid":{"rendered":"https:\/\/www.whitelabelcrowd.fund\/?p=10995"},"modified":"2022-05-27T13:33:32","modified_gmt":"2022-05-27T12:33:32","slug":"regtech-fur-ecsp","status":"publish","type":"post","link":"https:\/\/www.whitelabelcrowd.fund\/de\/regtech-fur-ecsp\/","title":{"rendered":"RegTech f\u00fcr europ\u00e4ische Crowdfunding-Dienstleister (ECSP)\u00a0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Im Zuge des\u202f<a href=\"https:\/\/ec.europa.eu\/info\/publications\/180308-action-plan-fintech_en\" target=\"_blank\" rel=\"noreferrer noopener\">FinTech-Aktionsplans<\/a> der Europ\u00e4ischen Kommission trat die\u202f<a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/EN\/TXT\/HTML\/?uri=CELEX:32020R1503&amp;from=EN#d1e3154-1-1\" target=\"_blank\" rel=\"noreferrer noopener\">Verordnung \u00fcber Europ\u00e4ische Crowdfunding-Dienstleister f\u00fcr Unternehmen<\/a>\u202fam 10.\u202fNovember 2021 EU-weit in Kraft.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Verordnung gibt einheitliche Vorschriften f\u00fcr die gesamte EU hinsichtlich der Bereitstellung von investmentbasiertem und kreditbasiertem Crowdfunding vor. Sie erm\u00f6glicht Plattformen, auf Grundlage eines einheitlichen Regelwerks eine EU-Lizenz zu beantragen, die gesch\u00e4ftliche Aktivit\u00e4ten in der gesamten EU erleichtert.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die neuen Vorschriften gelten gleichzeitig mit den erweiterten, seit dem\u202f<a href=\"https:\/\/www.fca.org.uk\/publication\/policy\/ps19-14.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Post-Implementation Review 2019<\/a> geltenden Vorschriften des Vereinigten K\u00f6nigreichs. Die Richtlinie PS19\/14 hat nach dem Scheitern von P2P-Plattformen diverse Schutzmechanismen eingef\u00fchrt.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">WLCF besitzt Erfahrung in den Bereichen Entwicklung, Pflege und Support von Plattformen f\u00fcr regulierte Unternehmen in diversen Gerichtsbarkeiten. Wir haben uns eingehend mit den neuen Vorschriften besch\u00e4ftigt. Neben zahlreichen Standardfunktionen wie der Integration einer \u00dcberpr\u00fcfung des Geldw\u00e4scheverbots, Kundengelder-Management, Datenschutz, Zugriffs- und Rechtemanagement, Pr\u00fcfprotokolle etc. haben wir Bedarf an einigen \u00c4nderungen der Plattform festgestellt, die bei unserem ersten ECSP-Kunden implementiert werden m\u00fcssen:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>&#8211; <strong>Automatische Generierung der Wesentlichen Anlegerinformationen<\/strong>\u202f\u2013 Derzeit wird ein Profil mit allen Pflichtangaben angezeigt. Wir haben ein PDF-Vorlagenformat erstellt, das diese Angaben in einem herunterladbaren PDF mit h\u00f6chstens sechs Seiten b\u00fcndelt, welches von Nutzer*innen gespeichert werden kann. Dieses muss auch bei Transaktionen auf dem sekund\u00e4ren Marktplatz bereitgestellt werden.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>&#8211; Nachweis der Kongruenz des Portfoliomanagements mit den Investorenmandaten<\/strong>\u202f\u2013 Eventuell wird von Plattformen ein Nachweis verlangt, dass sie angemessene Aufzeichnungen \u00fcber das Investorenmandat f\u00fchren. Dazu z\u00e4hlen l\u00fcckenlose Pr\u00fcfprotokolle \u00fcber \u00c4nderungen des Mandats. Plattformen m\u00fcssen k\u00fcnftig nachweisen, dass die Allokation von Investorengeldern im Einklang mit dem erteilten Mandate erfolgt.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>&#8211; <strong>Auszahlungsmanagement f\u00fcr Notfallgelder<\/strong>\u202f\u2013 Plattformen haben einen Ermessensspielraum. Es sind jedoch zahlreiche Pflichtmitteilungen zu versenden. Plattformen m\u00fcssen zudem ein geeignetes Protokoll zu den Hintergr\u00fcnden einer jeden Entscheidung f\u00fchren und eine faire Behandlung von Kund*innen belegen.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>&#8211; <strong>R\u00fccktrittsm\u00f6glichkeit innerhalb von vier Tagen\u202f<\/strong>\u2013 Muss gegeben sein, um dem Erfordernis der \u201aBedenkzeit\u2018 zu entsprechen.<\/li><\/ul>\n\n\n\n<ul class=\"wp-block-list\"><li>&#8211; <strong>Compliance-Pr\u00fcfungen f\u00fcr jedes Crowdfunding-Angebot\/-Projekt\u202f<\/strong>\u2013 Dabei handelt es sich um eine aktualisierte Liste der Compliance-Pr\u00fcfungen, die absolviert werden m\u00fcssen, w\u00e4hrend das Angebot den Workflow durchl\u00e4uft.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Diese \u00c4nderungen lassen sich relative einfach umsetzen und werden f\u00fcr unsere ersten ECSP-Kunden kostenlos vorgenommen.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie auf der Suche nach einem Compliance-Berater sind, der Sie bei der Antragstellung unterst\u00fctzt, sprechen Sie uns ruhig an. Dann stellen wir entsprechende Kontakte her. Wenden Sie sich aber auch gern an uns, wenn Sie Berater sind und f\u00fcr Ihre Kund*innen nach Tech-L\u00f6sungen suchen. Wir w\u00fcrden Sie gern n\u00e4her kennen lernen und eruieren, wie wir einander unterst\u00fctzen k\u00f6nnen.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Kurz gesagt: Die ESMA hat die wesentlichen Elemente f\u00fcr eine effektive Regulierung erfolgreich herausgearbeitet. Nun gilt es abzuwarten, wie die Aufsichtsbeh\u00f6rden bei der \u00dcberwachung der Branche zusammenarbeiten werden.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie ein erfahrenes Team suchen, das eine RegTech-L\u00f6sung bereitstellen kann, die den diversen Crowdfunding-Auflagen entspricht, sind Sie bei uns genau richtig. Wir unterst\u00fctzen Sie gern beim Go-Live Ihrer Plattform.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Zuge des\u202fFinTech-Aktionsplans der Europ\u00e4ischen Kommission trat die\u202fVerordnung \u00fcber Europ\u00e4ische Crowdfunding-Dienstleister f\u00fcr Unternehmen\u202fam 10.\u202fNovember 2021 EU-weit in Kraft.&nbsp; Die Verordnung gibt einheitliche Vorschriften f\u00fcr die gesamte EU hinsichtlich der Bereitstellung von investmentbasiertem und kreditbasiertem Crowdfunding vor. Sie erm\u00f6glicht Plattformen, auf Grundlage eines einheitlichen Regelwerks eine EU-Lizenz zu beantragen, die gesch\u00e4ftliche Aktivit\u00e4ten in der gesamten EU [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":9347,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[648,657,660,663,651,654,277,371,335,291,285,293,297],"tags":[],"class_list":["post-10995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-648","category-657","category-660","category-663","category-651","category-654","category-clients-de","category-company-uncategorized-de","category-company-de","category-compliance-de","category-industry-de-2","category-regulation-de","category-operators-de"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>RegTech f\u00fcr europ\u00e4ische Crowdfunding-Dienstleister (ECSP)\u00a0 - White Label Crowdfunding<\/title>\n<meta name=\"description\" content=\"WLCF besitzt Erfahrung in den Bereichen Entwicklung, Pflege und Support von Plattformen f\u00fcr regulierte Unternehmen in diversen Gerichtsbarkeiten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.whitelabelcrowd.fund\/de\/regtech-fur-ecsp\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RegTech f\u00fcr europ\u00e4ische Crowdfunding-Dienstleister (ECSP)\u00a0 - White Label Crowdfunding\" \/>\n<meta property=\"og:description\" content=\"WLCF besitzt Erfahrung in den Bereichen Entwicklung, Pflege und Support von Plattformen f\u00fcr regulierte Unternehmen in diversen Gerichtsbarkeiten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.whitelabelcrowd.fund\/de\/regtech-fur-ecsp\/\" \/>\n<meta property=\"og:site_name\" content=\"White Label Crowdfunding\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/whitelabelcrowdfunding\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-27T10:46:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-27T12:33:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.whitelabelcrowd.fund\/wp-content\/uploads\/2018\/05\/EU-flag.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"275\" \/>\n\t<meta property=\"og:image:height\" content=\"183\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Daniel Rajkumar\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Daniel Rajkumar\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/regtech-fur-ecsp\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/regtech-fur-ecsp\\\/\"},\"author\":{\"name\":\"Daniel Rajkumar\",\"@id\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/#\\\/schema\\\/person\\\/e5b285411bcf5c197d23f307535fa73a\"},\"headline\":\"RegTech f\u00fcr europ\u00e4ische Crowdfunding-Dienstleister (ECSP)\u00a0\",\"datePublished\":\"2022-05-27T10:46:57+00:00\",\"dateModified\":\"2022-05-27T12:33:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/regtech-fur-ecsp\\\/\"},\"wordCount\":520,\"publisher\":{\"@id\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/regtech-fur-ecsp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/EU-flag.jpg\",\"articleSection\":[\"277\",\"291\",\"293\",\"297\",\"335\",\"371\",\"Clients\",\"Company\",\"Company\",\"Compliance\",\"Industry\",\"Regulation\",\"Running a Platform\"],\"inLanguage\":\"de-DE\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/regtech-fur-ecsp\\\/\",\"url\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/regtech-fur-ecsp\\\/\",\"name\":\"RegTech f\u00fcr europ\u00e4ische Crowdfunding-Dienstleister (ECSP)\u00a0 - White Label Crowdfunding\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/regtech-fur-ecsp\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/regtech-fur-ecsp\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/EU-flag.jpg\",\"datePublished\":\"2022-05-27T10:46:57+00:00\",\"dateModified\":\"2022-05-27T12:33:32+00:00\",\"description\":\"WLCF besitzt Erfahrung in den Bereichen Entwicklung, Pflege und Support von Plattformen f\u00fcr regulierte Unternehmen in diversen Gerichtsbarkeiten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/regtech-fur-ecsp\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/regtech-fur-ecsp\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/regtech-fur-ecsp\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/EU-flag.jpg\",\"contentUrl\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/wp-content\\\/uploads\\\/2018\\\/05\\\/EU-flag.jpg\",\"width\":275,\"height\":183,\"caption\":\"EU flag\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/regtech-fur-ecsp\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RegTech f\u00fcr europ\u00e4ische Crowdfunding-Dienstleister (ECSP)\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/\",\"name\":\"White Label Crowdfunding\",\"description\":\"See your future possibilities bloom with the freedom and versatility of peer-to-peer investment and borrowing.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/#organization\"},\"alternateName\":\"White Label Crowdfunding\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/#organization\",\"name\":\"White Label Crowdfunding\",\"url\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/wlcf.png\",\"contentUrl\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/wlcf.png\",\"width\":308,\"height\":308,\"caption\":\"White Label Crowdfunding\"},\"image\":{\"@id\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/whitelabelcrowdfunding\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/#\\\/schema\\\/person\\\/e5b285411bcf5c197d23f307535fa73a\",\"name\":\"Daniel Rajkumar\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4622e080718ffaf1f609d027b76b8ce47a4dbcb3ba2b8cbf833abedd54a20b57?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4622e080718ffaf1f609d027b76b8ce47a4dbcb3ba2b8cbf833abedd54a20b57?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4622e080718ffaf1f609d027b76b8ce47a4dbcb3ba2b8cbf833abedd54a20b57?s=96&d=mm&r=g\",\"caption\":\"Daniel Rajkumar\"},\"url\":\"https:\\\/\\\/www.whitelabelcrowd.fund\\\/de\\\/author\\\/danrajkumar\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RegTech f\u00fcr europ\u00e4ische Crowdfunding-Dienstleister (ECSP)\u00a0 - White Label Crowdfunding","description":"WLCF besitzt Erfahrung in den Bereichen Entwicklung, Pflege und Support von Plattformen f\u00fcr regulierte Unternehmen in diversen Gerichtsbarkeiten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.whitelabelcrowd.fund\/de\/regtech-fur-ecsp\/","og_locale":"de_DE","og_type":"article","og_title":"RegTech f\u00fcr europ\u00e4ische Crowdfunding-Dienstleister (ECSP)\u00a0 - White Label Crowdfunding","og_description":"WLCF besitzt Erfahrung in den Bereichen Entwicklung, Pflege und Support von Plattformen f\u00fcr regulierte Unternehmen in diversen Gerichtsbarkeiten.","og_url":"https:\/\/www.whitelabelcrowd.fund\/de\/regtech-fur-ecsp\/","og_site_name":"White Label Crowdfunding","article_publisher":"https:\/\/www.facebook.com\/whitelabelcrowdfunding","article_published_time":"2022-05-27T10:46:57+00:00","article_modified_time":"2022-05-27T12:33:32+00:00","og_image":[{"width":275,"height":183,"url":"https:\/\/www.whitelabelcrowd.fund\/wp-content\/uploads\/2018\/05\/EU-flag.jpg","type":"image\/jpeg"}],"author":"Daniel Rajkumar","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Daniel Rajkumar","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.whitelabelcrowd.fund\/de\/regtech-fur-ecsp\/#article","isPartOf":{"@id":"https:\/\/www.whitelabelcrowd.fund\/de\/regtech-fur-ecsp\/"},"author":{"name":"Daniel Rajkumar","@id":"https:\/\/www.whitelabelcrowd.fund\/de\/#\/schema\/person\/e5b285411bcf5c197d23f307535fa73a"},"headline":"RegTech f\u00fcr europ\u00e4ische Crowdfunding-Dienstleister (ECSP)\u00a0","datePublished":"2022-05-27T10:46:57+00:00","dateModified":"2022-05-27T12:33:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.whitelabelcrowd.fund\/de\/regtech-fur-ecsp\/"},"wordCount":520,"publisher":{"@id":"https:\/\/www.whitelabelcrowd.fund\/de\/#organization"},"image":{"@id":"https:\/\/www.whitelabelcrowd.fund\/de\/regtech-fur-ecsp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.whitelabelcrowd.fund\/wp-content\/uploads\/2018\/05\/EU-flag.jpg","articleSection":["277","291","293","297","335","371","Clients","Company","Company","Compliance","Industry","Regulation","Running a Platform"],"inLanguage":"de-DE"},{"@type":"WebPage","@id":"https:\/\/www.whitelabelcrowd.fund\/de\/regtech-fur-ecsp\/","url":"https:\/\/www.whitelabelcrowd.fund\/de\/regtech-fur-ecsp\/","name":"RegTech f\u00fcr europ\u00e4ische Crowdfunding-Dienstleister (ECSP)\u00a0 - White Label Crowdfunding","isPartOf":{"@id":"https:\/\/www.whitelabelcrowd.fund\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.whitelabelcrowd.fund\/de\/regtech-fur-ecsp\/#primaryimage"},"image":{"@id":"https:\/\/www.whitelabelcrowd.fund\/de\/regtech-fur-ecsp\/#primaryimage"},"thumbnailUrl":"https:\/\/www.whitelabelcrowd.fund\/wp-content\/uploads\/2018\/05\/EU-flag.jpg","datePublished":"2022-05-27T10:46:57+00:00","dateModified":"2022-05-27T12:33:32+00:00","description":"WLCF besitzt Erfahrung in den Bereichen Entwicklung, Pflege und Support von Plattformen f\u00fcr regulierte Unternehmen in diversen Gerichtsbarkeiten.","breadcrumb":{"@id":"https:\/\/www.whitelabelcrowd.fund\/de\/regtech-fur-ecsp\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.whitelabelcrowd.fund\/de\/regtech-fur-ecsp\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.whitelabelcrowd.fund\/de\/regtech-fur-ecsp\/#primaryimage","url":"https:\/\/www.whitelabelcrowd.fund\/wp-content\/uploads\/2018\/05\/EU-flag.jpg","contentUrl":"https:\/\/www.whitelabelcrowd.fund\/wp-content\/uploads\/2018\/05\/EU-flag.jpg","width":275,"height":183,"caption":"EU flag"},{"@type":"BreadcrumbList","@id":"https:\/\/www.whitelabelcrowd.fund\/de\/regtech-fur-ecsp\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.whitelabelcrowd.fund\/de\/home\/"},{"@type":"ListItem","position":2,"name":"RegTech f\u00fcr europ\u00e4ische Crowdfunding-Dienstleister (ECSP)\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.whitelabelcrowd.fund\/de\/#website","url":"https:\/\/www.whitelabelcrowd.fund\/de\/","name":"White Label Crowdfunding","description":"See your future possibilities bloom with the freedom and versatility of peer-to-peer investment and borrowing.","publisher":{"@id":"https:\/\/www.whitelabelcrowd.fund\/de\/#organization"},"alternateName":"White Label Crowdfunding","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.whitelabelcrowd.fund\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/www.whitelabelcrowd.fund\/de\/#organization","name":"White Label Crowdfunding","url":"https:\/\/www.whitelabelcrowd.fund\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.whitelabelcrowd.fund\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.whitelabelcrowd.fund\/wp-content\/uploads\/2025\/05\/wlcf.png","contentUrl":"https:\/\/www.whitelabelcrowd.fund\/wp-content\/uploads\/2025\/05\/wlcf.png","width":308,"height":308,"caption":"White Label Crowdfunding"},"image":{"@id":"https:\/\/www.whitelabelcrowd.fund\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/whitelabelcrowdfunding"]},{"@type":"Person","@id":"https:\/\/www.whitelabelcrowd.fund\/de\/#\/schema\/person\/e5b285411bcf5c197d23f307535fa73a","name":"Daniel Rajkumar","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/secure.gravatar.com\/avatar\/4622e080718ffaf1f609d027b76b8ce47a4dbcb3ba2b8cbf833abedd54a20b57?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4622e080718ffaf1f609d027b76b8ce47a4dbcb3ba2b8cbf833abedd54a20b57?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4622e080718ffaf1f609d027b76b8ce47a4dbcb3ba2b8cbf833abedd54a20b57?s=96&d=mm&r=g","caption":"Daniel Rajkumar"},"url":"https:\/\/www.whitelabelcrowd.fund\/de\/author\/danrajkumar\/"}]}},"_links":{"self":[{"href":"https:\/\/www.whitelabelcrowd.fund\/de\/wp-json\/wp\/v2\/posts\/10995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.whitelabelcrowd.fund\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.whitelabelcrowd.fund\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.whitelabelcrowd.fund\/de\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.whitelabelcrowd.fund\/de\/wp-json\/wp\/v2\/comments?post=10995"}],"version-history":[{"count":3,"href":"https:\/\/www.whitelabelcrowd.fund\/de\/wp-json\/wp\/v2\/posts\/10995\/revisions"}],"predecessor-version":[{"id":11106,"href":"https:\/\/www.whitelabelcrowd.fund\/de\/wp-json\/wp\/v2\/posts\/10995\/revisions\/11106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.whitelabelcrowd.fund\/de\/wp-json\/wp\/v2\/media\/9347"}],"wp:attachment":[{"href":"https:\/\/www.whitelabelcrowd.fund\/de\/wp-json\/wp\/v2\/media?parent=10995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.whitelabelcrowd.fund\/de\/wp-json\/wp\/v2\/categories?post=10995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.whitelabelcrowd.fund\/de\/wp-json\/wp\/v2\/tags?post=10995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}